{"id":1667,"date":"2026-05-18T10:30:23","date_gmt":"2026-05-18T13:30:23","guid":{"rendered":"https:\/\/elcentinelaformosa.com\/?p=1667"},"modified":"2026-05-18T10:30:23","modified_gmt":"2026-05-18T13:30:23","slug":"salta-feroz-represion-contra-docentes","status":"publish","type":"post","link":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/","title":{"rendered":"SALTA: FEROZ REPRESION CONTRA DOCENTES"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1672\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0043-1.jpg?resize=300%2C300\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0043-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0043-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0043-1.jpg?w=708&amp;ssl=1 708w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Hace pocas horas, una gran marcha docente contra el represor Gustavo Saenz. Los manifestantes estar\u00edan siendo reprimidos con balas de goma.<\/p>\n<p>&nbsp;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1669\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?resize=300%2C285\" alt=\"\" width=\"300\" height=\"285\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?resize=300%2C285&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?w=720&amp;ssl=1 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>S\u00e1enz utilizar\u00eda en plena democracia el estilo de represion del &#8221; MODELO&#8221; formose\u00f1o. Como todos los autoritarios, S\u00e1enz se mofa de los docentes reclamantes, diciendo en sus discursos: &#8220;que dejen de llorar( los docentes), &#8220;si con esas pistolas juegan los chicos&#8221;<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1673\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0042.jpg?resize=300%2C295\" alt=\"\" width=\"300\" height=\"295\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0042.jpg?resize=300%2C295&amp;ssl=1 300w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0042.jpg?w=720&amp;ssl=1 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>La polic\u00eda del gobernador salte\u00f1o se r\u00ede de los manifestantes mientras los reprimen a golpes de tonfa y balas de goma, arremeten con todo no respetan ni la bandera que los manifestantes ponen frente de si.<\/p>\n<p>( ampliaremos)<\/p>\n<p id=\"rop\"><small>Originally posted 2023-05-30 07:22:13. <\/small><\/p>","protected":false},"excerpt":{"rendered":"<p>Hace pocas horas, una gran marcha docente contra el represor Gustavo Saenz. Los manifestantes estar\u00edan siendo reprimidos con balas de goma. &nbsp; S\u00e1enz utilizar\u00eda en plena democracia el estilo de represion del &#8221; MODELO&#8221; formose\u00f1o. Como todos los autoritarios, S\u00e1enz se mofa de los docentes reclamantes, diciendo en sus discursos: &#8220;que dejen de llorar( los&#8230; <a href=\"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/\">Read more: SALTA: FEROZ REPRESION CONTRA DOCENTES<\/a><\/p>\n","protected":false},"author":2,"featured_media":1669,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_815903348_815903348":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","h5ap_radio_sources":[],"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[459,6,77,1],"tags":[13,475,477,478,476,474],"class_list":["post-1667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derecho-ciudadano","category-el-centinela","category-redes","category-uncategorized","tag-argentina","tag-docentes","tag-reclamo-docente","tag-represion-policial-a-docentes-en-salta","tag-saenz","tag-salta"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Admin\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"EL CENTINELA | FORMOSA\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-18T13:30:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-18T13:30:23+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#article\",\"name\":\"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA\",\"headline\":\"SALTA: FEROZ REPRESION CONTRA DOCENTES\",\"author\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elcentinelaformosa.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG-20230529-WA0041.jpg?fit=720%2C685&ssl=1\",\"width\":720,\"height\":685},\"datePublished\":\"2026-05-18T10:30:23-03:00\",\"dateModified\":\"2026-05-18T10:30:23-03:00\",\"inLanguage\":\"es-AR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#webpage\"},\"articleSection\":\"Derecho ciudadano, El Centinela, redes, Uncategorized, argentina, docentes, reclamo docente, represi\\u00f3n policial a docentes en Salta, S\\u00e1enz, Salta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elcentinelaformosa.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"position\":2,\"name\":\"Uncategorized\",\"item\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/category\\\/uncategorized\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#listItem\",\"name\":\"SALTA: FEROZ REPRESION CONTRA DOCENTES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#listItem\",\"position\":3,\"name\":\"SALTA: FEROZ REPRESION CONTRA DOCENTES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/category\\\/uncategorized\\\/#listItem\",\"name\":\"Uncategorized\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/#organization\",\"name\":\"EL CENTINELA\",\"description\":\"FORMOSA\",\"url\":\"https:\\\/\\\/elcentinelaformosa.com\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/author\\\/admin\\\/\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdf04b169c13fc57aedf318e1d35c685b3e50334f5e40f1b0d3b11a1212096e1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#webpage\",\"url\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/\",\"name\":\"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/elcentinelaformosa.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/IMG-20230529-WA0041.jpg?fit=720%2C685&ssl=1\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#mainImage\",\"width\":720,\"height\":685},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/index.php\\\/2026\\\/05\\\/18\\\/salta-feroz-represion-contra-docentes\\\/#mainImage\"},\"datePublished\":\"2026-05-18T10:30:23-03:00\",\"dateModified\":\"2026-05-18T10:30:23-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/#website\",\"url\":\"https:\\\/\\\/elcentinelaformosa.com\\\/\",\"name\":\"EL CENTINELA\",\"description\":\"FORMOSA\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/elcentinelaformosa.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA","description":"","canonical_url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#article","name":"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA","headline":"SALTA: FEROZ REPRESION CONTRA DOCENTES","author":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/elcentinelaformosa.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?fit=720%2C685&ssl=1","width":720,"height":685},"datePublished":"2026-05-18T10:30:23-03:00","dateModified":"2026-05-18T10:30:23-03:00","inLanguage":"es-AR","mainEntityOfPage":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#webpage"},"isPartOf":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#webpage"},"articleSection":"Derecho ciudadano, El Centinela, redes, Uncategorized, argentina, docentes, reclamo docente, represi\u00f3n policial a docentes en Salta, S\u00e1enz, Salta"},{"@type":"BreadcrumbList","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com#listItem","position":1,"name":"Home","item":"https:\/\/elcentinelaformosa.com","nextItem":{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/#listItem","name":"Uncategorized"}},{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/#listItem","position":2,"name":"Uncategorized","item":"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/","nextItem":{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#listItem","name":"SALTA: FEROZ REPRESION CONTRA DOCENTES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#listItem","position":3,"name":"SALTA: FEROZ REPRESION CONTRA DOCENTES","previousItem":{"@type":"ListItem","@id":"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/#listItem","name":"Uncategorized"}}]},{"@type":"Organization","@id":"https:\/\/elcentinelaformosa.com\/#organization","name":"EL CENTINELA","description":"FORMOSA","url":"https:\/\/elcentinelaformosa.com\/"},{"@type":"Person","@id":"https:\/\/elcentinelaformosa.com\/index.php\/author\/admin\/#author","url":"https:\/\/elcentinelaformosa.com\/index.php\/author\/admin\/","name":"Admin","image":{"@type":"ImageObject","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bdf04b169c13fc57aedf318e1d35c685b3e50334f5e40f1b0d3b11a1212096e1?s=96&d=mm&r=g","width":96,"height":96,"caption":"Admin"}},{"@type":"WebPage","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#webpage","url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/","name":"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/elcentinelaformosa.com\/#website"},"breadcrumb":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#breadcrumblist"},"author":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/author\/admin\/#author"},"creator":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?fit=720%2C685&ssl=1","@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#mainImage","width":720,"height":685},"primaryImageOfPage":{"@id":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/#mainImage"},"datePublished":"2026-05-18T10:30:23-03:00","dateModified":"2026-05-18T10:30:23-03:00"},{"@type":"WebSite","@id":"https:\/\/elcentinelaformosa.com\/#website","url":"https:\/\/elcentinelaformosa.com\/","name":"EL CENTINELA","description":"FORMOSA","inLanguage":"es-AR","publisher":{"@id":"https:\/\/elcentinelaformosa.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"EL CENTINELA | FORMOSA","og:type":"article","og:title":"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA","og:url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/","article:published_time":"2026-05-18T13:30:23+00:00","article:modified_time":"2026-05-18T13:30:23+00:00","twitter:card":"summary_large_image","twitter:title":"SALTA: FEROZ REPRESION CONTRA DOCENTES | EL CENTINELA"},"aioseo_meta_data":{"post_id":"1667","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-30 10:09:52","updated":"2026-06-09 11:31:32","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/elcentinelaformosa.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/\" title=\"Uncategorized\">Uncategorized<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSALTA: FEROZ REPRESION CONTRA DOCENTES\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/elcentinelaformosa.com"},{"label":"Uncategorized","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/uncategorized\/"},{"label":"SALTA: FEROZ REPRESION CONTRA DOCENTES","link":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/salta-feroz-represion-contra-docentes\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/05\/IMG-20230529-WA0041.jpg?fit=720%2C685&ssl=1","jetpack-related-posts":[{"id":2076,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/04\/04\/ludopatia-en-las-aulas\/","url_meta":{"origin":1667,"position":0},"title":"LUDOPAT\u00cdA EN LAS AULAS","author":"Admin","date":"abril 4, 2026","format":false,"excerpt":"M\u00e1s all\u00e1 del juego LUDOPAT\u00cdA EN LAS AULAS UNA PROPUESTA DE FORMACI\u00d3N PARA QUE LOS DOCENTES LA PUEDAN ENFRENTAR En un contexto donde las apuestas en l\u00ednea y los juegos de azar ganan cada vez m\u00e1s terreno entre adolescentes y j\u00f3venes, la escuela emerge como un espacio clave para la\u2026","rel":"","context":"En &quot;Local&quot;","block_context":{"text":"Local","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250623-WA0007.jpg?fit=813%2C360&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250623-WA0007.jpg?fit=813%2C360&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250623-WA0007.jpg?fit=813%2C360&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250623-WA0007.jpg?fit=813%2C360&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":607,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/formosa-pide-libertad-para-las-personas-humanas-y-no-humanas\/","url_meta":{"origin":1667,"position":1},"title":"FORMOSA PIDE LIBERTAD PARA LAS PERSONAS HUMANAS Y NO HUMANAS","author":"Admin","date":"febrero 27, 2026","format":false,"excerpt":"El pueblo de Formosa unido con una sola consigna: FORMOSA LIBRE. Cu\u00e1nto significado en esa frase? Much\u00edsimos! Se pide libre circulaci\u00f3n, basta de represi\u00f3n, de autoritarismo. Se pide dignidad. Trabajo. Paz. Vivienda. Se sabe de personas y familias enteras en situaci\u00f3n de calle. Familias completas. Y esto incluye a los\u2026","rel":"","context":"En &quot;El Centinela&quot;","block_context":{"text":"El Centinela","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/el-centinela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/03\/Screenshot_20210310-1256372.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2064,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/04\/04\/promo-banco-de-formosa-dia-del-padre-12-al-15-de-junio\/","url_meta":{"origin":1667,"position":2},"title":"Promo Banco de Formosa d\u00eda del padre &#8211; 12 al 15 de Junio","author":"Admin","date":"abril 4, 2026","format":false,"excerpt":"Promo Banco Formosa D\u00eda del Padre \u2013 12 al 15 de Junio. 25% DE REINTEGRO y 6 CUOTAS SIN INTER\u00c9S Banco Formosa estar\u00e1 presente con esta promoci\u00f3n en uno de los momentos m\u00e1s significativos para las familias. Combina ahorro, comodidad y apoyo al comercio local. Del jueves 12 al domingo\u2026","rel":"","context":"En &quot;Local&quot;","block_context":{"text":"Local","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250612-WA0023.jpg?fit=1200%2C473&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250612-WA0023.jpg?fit=1200%2C473&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250612-WA0023.jpg?fit=1200%2C473&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250612-WA0023.jpg?fit=1200%2C473&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/06\/IMG-20250612-WA0023.jpg?fit=1200%2C473&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1972,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/06\/09\/frontera-formosa-salta-bajo-agua-de\/","url_meta":{"origin":1667,"position":3},"title":"FRONTERA FORMOSA &#8211; SALTA: FAMILIAS BAJO AGUA POR AVANCE DEL R\u00cdO PILCOMAYO","author":"Admin","date":"junio 9, 2026","format":false,"excerpt":"La realidad del Norte. Zona frontera Salta-Formosa. Todo bajo aguas del Pilcomayo . Escuelas, centros de salud, familias con ni\u00f1os y animales. El avance del agua se lleva todo lo que tienen. A m\u00e1s de 500 kil\u00f3metros de la capital salte\u00f1a, a Hito 1, donde residen unas veinte familias, todav\u00eda\u2026","rel":"","context":"En \"Animales de Formosa\"","block_context":{"text":"Animales de Formosa","link":"https:\/\/elcentinelaformosa.com\/index.php\/tag\/animales-de-formosa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/03\/20250323_235513-ANIMATION.gif?fit=582%2C579&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/03\/20250323_235513-ANIMATION.gif?fit=582%2C579&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2025\/03\/20250323_235513-ANIMATION.gif?fit=582%2C579&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":1535,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/05\/18\/jornada-murcielagos-seres-imprescindibles-para-nuestro-planeta\/","url_meta":{"origin":1667,"position":4},"title":"JORNADA: MURCI\u00c9LAGOS, SERES IMPRESCINDIBLES PARA NUESTRO PLANETA","author":"Admin","date":"mayo 18, 2026","format":false,"excerpt":"En el d\u00eda de ayer martes 20 de diciembre a las 18 hs de nuestro pa\u00eds , tuvo lugar la Jornada virtual : \u201cMurci\u00e9lagos : seres imprescindibles para nuestro planeta \u201c , organizada por el Instituto de Derecho Animal de Aidca (Asociaci\u00f3n Iberoamericana de Derecho, Cultura y Ambiente) cuya Coordinadora\u2026","rel":"","context":"En &quot;Derecho snimal&quot;","block_context":{"text":"Derecho snimal","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/derecho-snimal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2022\/12\/20221221_035750-ANIMATION-1.gif?fit=829%2C1032&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2022\/12\/20221221_035750-ANIMATION-1.gif?fit=829%2C1032&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2022\/12\/20221221_035750-ANIMATION-1.gif?fit=829%2C1032&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2022\/12\/20221221_035750-ANIMATION-1.gif?fit=829%2C1032&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":41,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/formosa-de-pie-en-defensa-del-animal-y-del-medio-ambiente-natural-y-social\/","url_meta":{"origin":1667,"position":5},"title":"FORMOSA DE PIE EN DEFENSA DEL ANIMAL Y DEL MEDIO AMBIENTE NATURAL Y SOCIAL","author":"olivera.ricardo26@hotmail.com","date":"febrero 27, 2026","format":false,"excerpt":"En Formosa se contin\u00faa llevando adelante diversas manifestaciones, en el lugar m\u00e1s p\u00fablico y neutral de la ciudad, la plaza de todos, la misma que lleva el nombre del libertador de Am\u00e9rica, el Gral San Mart\u00edn. Dichas manifestaciones hab\u00edan tenido desde el principio otro punto de encuentro: LA CASA DEL\u2026","rel":"","context":"En &quot;Local&quot;","block_context":{"text":"Local","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/09\/FORMOSA-DE-PIE-EN-DEFENSA-DEL-ANIMAL-Y-DEL-MEDIO-AMBIENTE-NATURAL-Y-SOCIAL.jpeg?fit=1040%2C701&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/09\/FORMOSA-DE-PIE-EN-DEFENSA-DEL-ANIMAL-Y-DEL-MEDIO-AMBIENTE-NATURAL-Y-SOCIAL.jpeg?fit=1040%2C701&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/09\/FORMOSA-DE-PIE-EN-DEFENSA-DEL-ANIMAL-Y-DEL-MEDIO-AMBIENTE-NATURAL-Y-SOCIAL.jpeg?fit=1040%2C701&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/09\/FORMOSA-DE-PIE-EN-DEFENSA-DEL-ANIMAL-Y-DEL-MEDIO-AMBIENTE-NATURAL-Y-SOCIAL.jpeg?fit=1040%2C701&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":1,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/1667\/revisions"}],"predecessor-version":[{"id":1674,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/1667\/revisions\/1674"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/media\/1669"}],"wp:attachment":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=1667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=1667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}