{"id":688,"date":"2026-02-27T11:02:37","date_gmt":"2026-02-27T14:02:37","guid":{"rendered":"https:\/\/elcentinelaformosa.com\/?p=688"},"modified":"2026-02-27T11:02:37","modified_gmt":"2026-02-27T14:02:37","slug":"formosa-rinas-de-gallos-delitos-e-impunidad","status":"publish","type":"post","link":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/formosa-rinas-de-gallos-delitos-e-impunidad\/","title":{"rendered":"FORMOSA: RI\u00d1AS DE GALLOS, MALTRATO A ANCIANOS E IMPUNIDAD"},"content":{"rendered":"<p style=\"padding-left: 40px;\">En Formosa, abundan denuncias y pruebas contra la ri\u00f1a de animales organizadas por mafias enquistadas y protegidas por el manto de impunidad que caracteriza a la provincia desde hace muchos a\u00f1os.<\/p>\n<p style=\"padding-left: 40px;\">Se denuncia a los organizadores de las ri\u00f1as de gallos en Formosa, la justicia mira para otro lado. No escucha, no le importa? Deber\u00eda. La Ley Nacional 14346 es real, existe.\u00a0 Quienes avanzan sometiendo a los animales a los actos m\u00e1s crueles, violentos, salvajes que existen y\u00a0 pisoteando la legislaci\u00f3n deber\u00edan atenerse a las consecuencias. En un Estado normal. D\u00f3nde la divisi\u00f3n de poderes es la base de la democracia y una garant\u00eda para las personas de bien.<\/p>\n<p>Ayer, iniciado el mes junio una mujer anciana de 83 a\u00f1os de edad de esta ciudad Barrio Eva Per\u00f3n fue la v\u00edctima de una golpiza por parte del hijo.<\/p>\n<p>El atacante es justamente uno de los organizadores de ri\u00f1as de gallos en Formosa.<\/p>\n<p>Seg\u00fan las fuentes, tambi\u00e9n el maltratador es el administrador de la pensi\u00f3n de su se\u00f1ora madre.<\/p>\n<p>Los especialistas que analizan la conducta psicopatologica de estos seres que disfrutan ver sufrimiento y sangre,\u00a0 coinciden siempre en una conclusi\u00f3n: el maltratador de animales tambi\u00e9n lo proyecta m\u00e1s adelante hacia las personas. Por lo general, sus v\u00edctimas son justamente quienes no pueden defenderse. (Conferencia virtual a cargo de la doctora especialista en protecci\u00f3n animal, Laura Velasco, a\u00f1o 2021)<\/p>\n<p>Entre el d\u00eda de ayer y de hoy circulan por las redes, el v\u00eddeo de una anciana que relata como su hijo la maltrata f\u00edsica y emocionalmente, porque solo siente temor cuando se le acerca.<\/p>\n<p>El oscuro y sanguinario personaje que desde hace mucho tiempo viene lucrando con la sangre y el dolor de los animales que se desangran en dichas ri\u00f1as de gallos, vive en la ciudad de Formosa, en el barrio Eva Per\u00f3n, maltrata a su madre y administra a su antojo la magra pensi\u00f3n de la anciana,<\/p>\n<p>Por si alguno no conoce las caracter\u00edsticas de una ri\u00f1a de animales, el el acto m\u00e1s perverso, cruel y sangriento al cu\u00e1l se somete a un animal. Es obligado a pelear hasta matar al otro o morir. Una forma de esclavitud que no les permite vivir conforme a su naturaleza, sino que lo forzan\u00a0 al animal\u00a0 a tener la m\u00e1xima agresividad para llenar los bolsillos de sus &#8220;due\u00f1os&#8221; . Es delito. Tambi\u00e9n es delito participar indirectamente de estos hechos, asimismo, saber d\u00f3nde y cuando se realizan y no denunciar. Quienes tienen esa informaci\u00f3n pasan a ser c\u00f3mplices de un hecho aberrante<\/p>\n<p>Son\u00a0 realizadas por mafias que se inquistan en lugares alejados y que estar\u00edan\u00a0 impunemente protegidos por el poder de turno. La pandemia y las restricciones no rigen para ellos. Al vivir al margen de la Ley poco importa un DNI presidencial.<\/p>\n<p>Mientras se espera que quienes deben garantizar el orden y la justicia, los gallos son obligados a masacrarse entre ellos con espuelas, pu\u00f1ales de acero y cualquier objeto cortante que los s\u00e1dicos apostadores de la muerte agregan a los espolones naturales que los animales tienen al nacer.<\/p>\n<p>El acto m\u00e1s atroz sangriento, vil y cobarde llevado a cabo por personas tan inescrupulosas.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-701\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424694671756466109762028387.png?resize=700%2C671\" alt=\"\" width=\"700\" height=\"671\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424694671756466109762028387.png?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424694671756466109762028387.png?resize=300%2C288&amp;ssl=1 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>DENUNCIAS EFECTUADAS:<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-700\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424419161105637555021731646.png?resize=671%2C253\" alt=\"\" width=\"671\" height=\"253\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424419161105637555021731646.png?w=671&amp;ssl=1 671w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226424419161105637555021731646.png?resize=300%2C113&amp;ssl=1 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/p>\n<p>La proteccionista y rescatista titular de &#8220;Justicia por Athenas&#8221; Se\u00f1ora Elizabeth Gonz\u00e1lez, anteriormente ha denunciado estos crueles actos. Ha aportado informaci\u00f3n y pruebas a las denuncias. Sin embargo, los procedimientos efectuados por la justicia solo favorecieron a los organizadores de actos de crueldad contra los animales. Al asistir cuando ya hab\u00eda finalizado, se hab\u00eda limpiado el lugar.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-692\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123080901285484251348036188.png?resize=700%2C1048\" alt=\"\" width=\"700\" height=\"1048\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123080901285484251348036188.png?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123080901285484251348036188.png?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123080901285484251348036188.png?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123080901285484251348036188.png?resize=513%2C768&amp;ssl=1 513w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/>All\u00ed queda la duda de quienes pagan los salarios de los funcionarios con sus impuestos&#8230;.\u00a0 La justicia realmente funciona o solo es un brazo m\u00e1s del ejecutivo? Porque en estos lugares donde se derrama sangre inocente por un par de billetes, solo se han visto por fuera camionetas de alta gama, importadas, que caracterizan a Juan pueblo, sino a quienes dicen representar&#8230;.<\/p>\n<ol>\n<li><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-689\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226117073158142778254542270708.png?resize=700%2C875\" alt=\"\" width=\"700\" height=\"875\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226117073158142778254542270708.png?w=720&amp;ssl=1 720w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226117073158142778254542270708.png?resize=240%2C300&amp;ssl=1 240w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226117073158142778254542270708.png?resize=614%2C768&amp;ssl=1 614w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/li>\n<\/ol>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignright size-full wp-image-694\" src=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123553491105037124281216336.png?resize=700%2C535\" alt=\"\" width=\"700\" height=\"535\" srcset=\"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123553491105037124281216336.png?w=703&amp;ssl=1 703w, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226123553491105037124281216336.png?resize=300%2C229&amp;ssl=1 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Hola se que no es el lugar pero no me quedo de otra que subir aca nos cansamos de denunciar. Ella es mi vecina el maltratada por su hijo desde hace mucho tiempo y nadie le hace caso llamamos a todos lados y nadie hace caso van a esperar que le maten ella tiene 83 a\u00f1os de edad y tiene un solo hijo que es el sinverg\u00fcenza que no trabaja y le come el sueldo a su mam\u00e1 y encima le maltrata le pega no le da de comer a veces todos los vecinos saben. Y ahora tiene su mujer este sinverg\u00fcenza y conjunto con ella le maltratan la casa es de la se\u00f1ora no tiene m\u00e1s familia que solamente a el.. ella vive en el barrio Eva peron mz79 casa22 si alguien puede ayudarle ya no da m\u00e1s esta se\u00f1ora. El hijo no trabaja vive de ella y hace pelea con los gallos de ri\u00f1as.. y cuando pierde viene y remata por ella. Esta muy traumada vive mal ni se vacuno no se hace ver, ni un chequeo se puede hacer por que el no le deja. Por favor que alguien la venga a ver ella por miedo a el no dice nada. Pero aca en el video dijo todo que le pega. Hasta la empleada que trabajan ah\u00ed saben pero no pueden hacer nada..<\/p><\/blockquote>\n<p id=\"rop\"><small>Originally posted 2021-06-02 02:33:13. <\/small><\/p>","protected":false},"excerpt":{"rendered":"<p>En Formosa, abundan denuncias y pruebas contra la ri\u00f1a de animales organizadas por mafias enquistadas y protegidas por el manto de impunidad que caracteriza a la provincia desde hace muchos a\u00f1os. Se denuncia a los organizadores de las ri\u00f1as de gallos en Formosa, la justicia mira para otro lado. No escucha, no le importa? Deber\u00eda&#8230;. <a href=\"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/formosa-rinas-de-gallos-delitos-e-impunidad\/\">Read more: FORMOSA: RI\u00d1AS DE GALLOS, MALTRATO A ANCIANOS E IMPUNIDAD<\/a><\/p>\n","protected":false},"author":2,"featured_media":689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"initial","rop_publish_now_accounts":{"twitter_815903348_815903348":""},"rop_publish_now_history":[],"rop_publish_now_status":"pending","h5ap_radio_sources":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,5,77,1],"tags":[7,85,30,12,163,161,10,22,164,162,95,24,38,160],"class_list":["post-688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-centinela","category-local","category-redes","category-uncategorized","tag-bastadefalsassoluciones","tag-activistas","tag-alberto-fernandez","tag-centinela-formosa","tag-criminales-de-formosa","tag-delitos","tag-formosa","tag-gildo-insfran","tag-golpeador-de-ancianas","tag-ley-14346","tag-mafias-en-formosa","tag-megagranjas","tag-poder-gubernamental","tag-rinas-de-gallos"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/06\/wp-16226117073158142778254542270708.png?fit=720%2C900&ssl=1","jetpack-related-posts":[{"id":326,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/actos-de-intimidacion-desde-la-justicia-de-formosa-contra-respetable-rescatista\/","url_meta":{"origin":688,"position":0},"title":"FORMOSA: INTENTAR\u00cdAN INTIMIDAR A RESCATISTA A TRAV\u00c9S DE LA JUSTICIA","author":"Admin","date":"febrero 27, 2026","format":"image","excerpt":"PARA MUCHOS, EL PODER POL\u00cdTICO DE TURNO DE LA PROVINCIA\u00a0 ESTAR\u00cdA INTENTANDO INTIMIDAR A PROTECCIONISTA ANIMAL QUE LUCHA PARA EVITAR EL MALTRATO DE TODAS LAS ESPECIES.\u00a0Seg\u00fan las fuentes, ser\u00eda como un \"\u00faltimo manotazo de qui\u00e9n se ahoga\" . El ataque del poder politico local, mediante mecanismos funcionales buscar\u00eda intimidar y\/ofrenar\u2026","rel":"","context":"En &quot;El Centinela&quot;","block_context":{"text":"El Centinela","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/el-centinela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/11\/screenshot_20201112-02042123874162245420477335..jpg?fit=704%2C612&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/11\/screenshot_20201112-02042123874162245420477335..jpg?fit=704%2C612&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/11\/screenshot_20201112-02042123874162245420477335..jpg?fit=704%2C612&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2020\/11\/screenshot_20201112-02042123874162245420477335..jpg?fit=704%2C612&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1107,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/04\/01\/formosa-el-colorado-habria-negacion-de-justicia-para-los-animales-a-pesar-de-la-ley-nacional\/","url_meta":{"origin":688,"position":1},"title":"FORMOSA: EL COLORADO. HABR\u00cdA NEGACI\u00d3N DE JUSTICIA PARA LOS ANIMALES A PESAR DE LA LEY NACIONAL?","author":"Admin","date":"abril 1, 2026","format":false,"excerpt":"FORMOSA: EL COLORADO: ESTA PERSONA NO HUMANA NECESITA AYUDA Y DE MANERA URGENTE. EL CAN HACE M\u00c1S DE UN A\u00d1O SE HALLARIA SIENDO V\u00cdCTIMA DE MALOS TRATOS, COMO POR EJEMPLO QUE SE HALLAR\u00cdA ATADO CON CADENA Y CANDADO. ABANDONADO EN UNA CASA DESHABITADA. Y SIN ATENCI\u00d3N ADECUADA , COMO LO\u2026","rel":"","context":"En &quot;Derecho snimal&quot;","block_context":{"text":"Derecho snimal","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/derecho-snimal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/09\/IMG-20210922-WA0090.jpg?fit=720%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/09\/IMG-20210922-WA0090.jpg?fit=720%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/09\/IMG-20210922-WA0090.jpg?fit=720%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2021\/09\/IMG-20210922-WA0090.jpg?fit=720%2C800&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1762,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/01\/04\/formosa-pozo-del-tigre-dolor-y-muerte-por-envenenamiento-masivo\/","url_meta":{"origin":688,"position":2},"title":"FORMOSA, POZO DEL TIGRE: DOLOR Y MUERTE POR ENVENENAMIENTO MASIVO","author":"Admin","date":"enero 4, 2026","format":false,"excerpt":"La localidad del oeste formose\u00f1o denominada Pozo del Tigre donde parecer\u00eda no existir la ley, especialmente la ley Nacional 14346, una vez m\u00e1s, fue testigo callado de crueldad contra\u00a0 personas no humanas. Hace pocos d\u00edas en la misma localidad que asesinaran a palazos a un caballo atado a un palenque\u2026","rel":"","context":"En &quot;El Centinela&quot;","block_context":{"text":"El Centinela","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/el-centinela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/01\/IMG-20240104-WA0009.jpg?fit=1200%2C903&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/01\/IMG-20240104-WA0009.jpg?fit=1200%2C903&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/01\/IMG-20240104-WA0009.jpg?fit=1200%2C903&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/01\/IMG-20240104-WA0009.jpg?fit=1200%2C903&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/01\/IMG-20240104-WA0009.jpg?fit=1200%2C903&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1677,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/01\/04\/hablemos-de-derecho-animal\/","url_meta":{"origin":688,"position":3},"title":"HABLEMOS DE DERECHO ANIMAL","author":"Admin","date":"enero 4, 2026","format":false,"excerpt":"Desde Argentina la Dra. Laura Cecilia Velasco, Especialista y pionera mundial sobre Derecho Animal realiz\u00f3 una nueva presentaci\u00f3n como cada semana de su programa \" Hablemos de derecho animal\" El pasado Mi\u00e9rcoles 31 de mayo\u00a0 se llev\u00f3 a cabo una transmisi\u00f3n \u00a0en vivo en las plataformas digitales de IIECtv |\u2026","rel":"","context":"En &quot;Congresos y Conferencias&quot;","block_context":{"text":"Congresos y Conferencias","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/congresos-y-conferencias\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/06\/Screenshot_20230601-132213.png?fit=1080%2C906&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/06\/Screenshot_20230601-132213.png?fit=1080%2C906&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/06\/Screenshot_20230601-132213.png?fit=1080%2C906&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/06\/Screenshot_20230601-132213.png?fit=1080%2C906&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2023\/06\/Screenshot_20230601-132213.png?fit=1080%2C906&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":1450,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/04\/01\/formosa-para-los-animales-ni-justicia\/","url_meta":{"origin":688,"position":4},"title":"FORMOSA: PARA LOS ANIMALES NI JUSTICIA?","author":"Admin","date":"abril 1, 2026","format":false,"excerpt":"CRECE LA PREOCUPACI\u00d3N ENTRE LOS ACTIVISTAS Y PROTECCIONISTAS Luego que tomara estado p\u00fablico el aberrante, salvaje y atroz hecho sucedido en el Paraje Potrero de los caballos, departamento Laishi de Formosa sobre la violaci\u00f3n y ultraje a una perrita por parte de un sujeto de apellido Quintana, tambi\u00e9n cabe recordar\u2026","rel":"","context":"En &quot;Derecho snimal&quot;","block_context":{"text":"Derecho snimal","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/derecho-snimal\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2022\/09\/Screenshot_20220903-1436542.png?fit=487%2C418&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1869,"url":"https:\/\/elcentinelaformosa.com\/index.php\/2026\/02\/27\/la-fundacion-spa-denuncia-inaccion-ante-actos-de-crueldad-contra-los-animales-en-formosa\/","url_meta":{"origin":688,"position":5},"title":"LA FUNDACI\u00d3N SPA DENUNCIA INACCI\u00d3N ANTE ACTOS DE CRUELDAD CONTRA LOS ANIMALES EN FORMOSA","author":"Admin","date":"febrero 27, 2026","format":false,"excerpt":"Ante reiterados pedidos solicitando la intervenci\u00f3n de las autoridades competentes sin respuesta, la presidente de la Fundaci\u00f3n SPA Virginia Fern\u00e1ndez present\u00f3 por escrito los fundamentos sobre el cuidado de las especies protegidas en Formosa. Los aberrantes hechos cometidos contra las diferentes especies, yaguaret\u00e9, oso hormiguero, la destrucci\u00f3n de los espejos\u2026","rel":"","context":"En &quot;El Centinela&quot;","block_context":{"text":"El Centinela","link":"https:\/\/elcentinelaformosa.com\/index.php\/category\/el-centinela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/08\/IMG-20240805-WA0018.jpg?fit=900%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/08\/IMG-20240805-WA0018.jpg?fit=900%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/08\/IMG-20240805-WA0018.jpg?fit=900%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/elcentinelaformosa.com\/wp-content\/uploads\/2024\/08\/IMG-20240805-WA0018.jpg?fit=900%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":4,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"predecessor-version":[{"id":702,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/posts\/688\/revisions\/702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/media\/689"}],"wp:attachment":[{"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcentinelaformosa.com\/index.php\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}